{"id":628518,"date":"2026-01-19T08:12:34","date_gmt":"2026-01-19T07:12:34","guid":{"rendered":"https:\/\/cronologia-universale.it\/july-7-2005\/"},"modified":"2026-01-19T08:12:34","modified_gmt":"2026-01-19T07:12:34","slug":"march-28-2000","status":"publish","type":"post","link":"https:\/\/cronologia-universale.it\/en\/march-28-2000\/","title":{"rendered":"March 28, 2000"},"content":{"rendered":"<p>Daimler-Chrysler buys 33.4% of Mitsubishi, gaining control of it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daimler-Chrysler buys 33.4% of Mitsubishi, gaining control of it<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-628518","post","type-post","status-publish","format-standard","hentry","category-vg-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>March 28, 2000 - Cronologia Universale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cronologia-universale.it\/en\/march-28-2000\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"March 28, 2000 - Cronologia Universale\" \/>\n<meta property=\"og:description\" content=\"Daimler-Chrysler buys 33.4% of Mitsubishi, gaining control of it\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cronologia-universale.it\/en\/march-28-2000\/\" \/>\n<meta property=\"og:site_name\" content=\"Cronologia Universale\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T07:12:34+00:00\" \/>\n<meta name=\"author\" content=\"Rick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rick\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cronologia-universale.it\/en\/march-28-2000\/\",\"url\":\"https:\/\/cronologia-universale.it\/en\/march-28-2000\/\",\"name\":\"March 28, 2000 - Cronologia Universale\",\"isPartOf\":{\"@id\":\"https:\/\/cronologia-universale.it\/#website\"},\"datePublished\":\"2026-01-19T07:12:34+00:00\",\"author\":{\"@id\":\"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03\"},\"breadcrumb\":{\"@id\":\"https:\/\/cronologia-universale.it\/en\/march-28-2000\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cronologia-universale.it\/en\/march-28-2000\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cronologia-universale.it\/en\/march-28-2000\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cronologia-universale.it\/en\/universal-cronology\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"March 28, 2000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cronologia-universale.it\/#website\",\"url\":\"https:\/\/cronologia-universale.it\/\",\"name\":\"Cronologia Universale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cronologia-universale.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03\",\"name\":\"Rick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cronologia-universale.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g\",\"caption\":\"Rick\"},\"sameAs\":[\"http:\/\/cronologia-universale.it\"],\"url\":\"https:\/\/cronologia-universale.it\/en\/author\/rick\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"March 28, 2000 - Cronologia Universale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cronologia-universale.it\/en\/march-28-2000\/","og_locale":"en_US","og_type":"article","og_title":"March 28, 2000 - Cronologia Universale","og_description":"Daimler-Chrysler buys 33.4% of Mitsubishi, gaining control of it","og_url":"https:\/\/cronologia-universale.it\/en\/march-28-2000\/","og_site_name":"Cronologia Universale","article_published_time":"2026-01-19T07:12:34+00:00","author":"Rick","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rick"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cronologia-universale.it\/en\/march-28-2000\/","url":"https:\/\/cronologia-universale.it\/en\/march-28-2000\/","name":"March 28, 2000 - Cronologia Universale","isPartOf":{"@id":"https:\/\/cronologia-universale.it\/#website"},"datePublished":"2026-01-19T07:12:34+00:00","author":{"@id":"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03"},"breadcrumb":{"@id":"https:\/\/cronologia-universale.it\/en\/march-28-2000\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cronologia-universale.it\/en\/march-28-2000\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cronologia-universale.it\/en\/march-28-2000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cronologia-universale.it\/en\/universal-cronology\/"},{"@type":"ListItem","position":2,"name":"March 28, 2000"}]},{"@type":"WebSite","@id":"https:\/\/cronologia-universale.it\/#website","url":"https:\/\/cronologia-universale.it\/","name":"Cronologia Universale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cronologia-universale.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03","name":"Rick","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cronologia-universale.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g","caption":"Rick"},"sameAs":["http:\/\/cronologia-universale.it"],"url":"https:\/\/cronologia-universale.it\/en\/author\/rick\/"}]}},"_links":{"self":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts\/628518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/comments?post=628518"}],"version-history":[{"count":2,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts\/628518\/revisions"}],"predecessor-version":[{"id":693645,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts\/628518\/revisions\/693645"}],"wp:attachment":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/media?parent=628518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/categories?post=628518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/tags?post=628518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}