{"id":627819,"date":"2026-01-19T00:49:40","date_gmt":"2026-01-18T23:49:40","guid":{"rendered":"https:\/\/cronologia-universale.it\/1997-2\/"},"modified":"2026-01-19T00:49:40","modified_gmt":"2026-01-18T23:49:40","slug":"1989-5","status":"publish","type":"post","link":"https:\/\/cronologia-universale.it\/en\/1989-5\/","title":{"rendered":"1989"},"content":{"rendered":"<p>The number of known asteroids has risen to 10,000. There were 1,000 in 1921. In 2020, there will be 853,561.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The number of known asteroids has risen to 10,000. There were 1,000 in 1921. In&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-627819","post","type-post","status-publish","format-standard","hentry","category-as-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1989 - Cronologia Universale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cronologia-universale.it\/en\/1989-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1989 - Cronologia Universale\" \/>\n<meta property=\"og:description\" content=\"The number of known asteroids has risen to 10,000. There were 1,000 in 1921. In...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cronologia-universale.it\/en\/1989-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Cronologia Universale\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-18T23:49:40+00:00\" \/>\n<meta name=\"author\" content=\"Rick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rick\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cronologia-universale.it\/en\/1989-5\/\",\"url\":\"https:\/\/cronologia-universale.it\/en\/1989-5\/\",\"name\":\"1989 - Cronologia Universale\",\"isPartOf\":{\"@id\":\"https:\/\/cronologia-universale.it\/#website\"},\"datePublished\":\"2026-01-18T23:49:40+00:00\",\"author\":{\"@id\":\"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03\"},\"breadcrumb\":{\"@id\":\"https:\/\/cronologia-universale.it\/en\/1989-5\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cronologia-universale.it\/en\/1989-5\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cronologia-universale.it\/en\/1989-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cronologia-universale.it\/en\/universal-cronology\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1989\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cronologia-universale.it\/#website\",\"url\":\"https:\/\/cronologia-universale.it\/\",\"name\":\"Cronologia Universale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cronologia-universale.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03\",\"name\":\"Rick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/cronologia-universale.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g\",\"caption\":\"Rick\"},\"sameAs\":[\"http:\/\/cronologia-universale.it\"],\"url\":\"https:\/\/cronologia-universale.it\/en\/author\/rick\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1989 - Cronologia Universale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cronologia-universale.it\/en\/1989-5\/","og_locale":"en_US","og_type":"article","og_title":"1989 - Cronologia Universale","og_description":"The number of known asteroids has risen to 10,000. There were 1,000 in 1921. In...","og_url":"https:\/\/cronologia-universale.it\/en\/1989-5\/","og_site_name":"Cronologia Universale","article_published_time":"2026-01-18T23:49:40+00:00","author":"Rick","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rick"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cronologia-universale.it\/en\/1989-5\/","url":"https:\/\/cronologia-universale.it\/en\/1989-5\/","name":"1989 - Cronologia Universale","isPartOf":{"@id":"https:\/\/cronologia-universale.it\/#website"},"datePublished":"2026-01-18T23:49:40+00:00","author":{"@id":"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03"},"breadcrumb":{"@id":"https:\/\/cronologia-universale.it\/en\/1989-5\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cronologia-universale.it\/en\/1989-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cronologia-universale.it\/en\/1989-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cronologia-universale.it\/en\/universal-cronology\/"},{"@type":"ListItem","position":2,"name":"1989"}]},{"@type":"WebSite","@id":"https:\/\/cronologia-universale.it\/#website","url":"https:\/\/cronologia-universale.it\/","name":"Cronologia Universale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cronologia-universale.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cronologia-universale.it\/#\/schema\/person\/f510f53010edc7a70b16caecf1c4af03","name":"Rick","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cronologia-universale.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f707c665808696c8fa12345661bf0ef3aa60982ce3781ec6cc5b16b7b828ba8?s=96&d=mm&r=g","caption":"Rick"},"sameAs":["http:\/\/cronologia-universale.it"],"url":"https:\/\/cronologia-universale.it\/en\/author\/rick\/"}]}},"_links":{"self":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts\/627819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/comments?post=627819"}],"version-history":[{"count":2,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts\/627819\/revisions"}],"predecessor-version":[{"id":692946,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/posts\/627819\/revisions\/692946"}],"wp:attachment":[{"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/media?parent=627819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/categories?post=627819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cronologia-universale.it\/en\/wp-json\/wp\/v2\/tags?post=627819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}